{"id":11845,"date":"2025-01-08T16:04:48","date_gmt":"2025-01-08T08:04:48","guid":{"rendered":"https:\/\/www.tigerandtech.com\/?p=11845"},"modified":"2025-01-08T16:04:51","modified_gmt":"2025-01-08T08:04:51","slug":"gu_shi_li_de_nan_jing_ban_kuai","status":"publish","type":"post","link":"https:\/\/www.tigerandtech.com\/de\/gu_shi_li_de_nan_jing_ban_kuai\/","title":{"rendered":"Nanjing Board auf dem Aktienmarkt"},"content":{"rendered":"<p><em>Von der Kent-Aktien landete auf der Growth Enterprise Market (GEM), um die erste b\u00f6rsennotierte Ningbo Unternehmen in diesem Jahr, um die T\u00fcr Ask und Shenghe Biologicals wurden auf dem Hauptbrett der Hongkonger B\u00f6rse in einem Monat Intervall, und dann auf dem Hauptbrett der Shanghai Stock Exchange b\u00f6rsennotierten Ningbo Unternehmen Longbao Science and Technology an der Hongkonger B\u00f6rse zu realisieren, die \"A + H\"-Aktien Doppel-Rad-Antrieb. ......<\/em><\/p>\n\n\n\n<p>Kurz nach 2024<\/p>\n\n\n\n<p>Kapitalm\u00e4rkte \"Nanjing Plate\" Spannend<\/p>\n\n\n\n<p>Helle Flecken erscheinen h\u00e4ufig<\/p>\n\n\n\n<p>Die neuesten Daten zeigen, dass<\/p>\n\n\n\n<p>2024<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die Stadt hat vier neue in- und ausl\u00e4ndische b\u00f6rsennotierte Unternehmen mit einem Gesamtvolumen von 1,661 Milliarden Yuan an die B\u00f6rse gebracht.<strong>Damit ist die Gesamtzahl der in- und ausl\u00e4ndischen b\u00f6rsennotierten Unternehmen in der Stadt auf 164 gestiegen.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>In diesem Jahr wurden 7 neue Unternehmen an der Neuen Dritten B\u00f6rse und 46 Unternehmen an der Provinzb\u00f6rse notiert.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dar\u00fcber hinaus wurden zwei \u00f6ffentliche Infrastruktur-REITs, Jianye Industrial Park und Transportation Expressway, genehmigt und emittiert, die insgesamt 3,748 Milliarden RMB einbrachten.<\/li>\n<\/ul>\n\n\n\n<p>In Nanjing werden durch die F\u00f6rderung der hochwertigen Entwicklung b\u00f6rsennotierter Unternehmen, die F\u00f6rderung und Unterst\u00fctzung von Fusionen und \u00dcbernahmen und die Umstrukturierung von Unternehmen sowie die Konzentration auf das Listenmanagement von Unternehmen, die an der B\u00f6rse notiert werden sollen, rasch eine Reihe hochwertiger Unternehmen gegr\u00fcndet und die \"Nanjing-Platte\" des Kapitalmarktes weiter ausgebaut.<strong>0<\/strong><strong>1<\/strong><\/p>\n\n\n\n<p><strong>den Beginn des Jahres begr\u00fc\u00dfen<\/strong><\/p>\n\n\n\n<p><strong>Der \"A+H\"-Doppelradantrieb beschleunigt die Globalisierung der Unternehmen in Ningbo<\/strong><\/p>\n\n\n\n<p>Zu Beginn des neuen Jahres wird die einheimische Lithiumindustrie eine wichtige Nachricht verk\u00fcnden.<\/p>\n\n\n\n<p>Lithium Source New Energy, die Holding-Tochtergesellschaft des b\u00f6rsennotierten Unternehmens Longpan Technology mit Sitz in Ningbo, hat offiziell ein langfristiges strategisches Kooperationsabkommen mit Zhuhai Guanyu, dem weltweit f\u00fchrenden Anbieter von Lithium-Ionen-Polymerbatterien, unterzeichnet, das Longpan Technology den Weg in das Jahr 2025 ebnet.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg\" alt=\"\" class=\"wp-image-11846\" style=\"width:840px;height:auto\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg 800w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243-300x169.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243-768x432.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243-18x10.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Ein Blick auf die Lithium Source New Energy Fabrik<\/p>\n\n\n\n<p>de facto<\/p>\n\n\n\n<p>Longbian Technology hat in letzter Zeit gute Nachrichten erhalten.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mehr als zehn Tage vor, Lithium Quelle der neuen Energie und LG New Energy \u00fcberarbeitet die zuvor unterzeichneten 160.000 Tonnen Lithium-Eisen-Phosphat-Kathoden-Material Handelsvolumen, die Erh\u00f6hung auf 260.000 Tonnen, ist der gesamte Marktpreis in der N\u00e4he von RMB 10 Milliarden, die globale Lithium-Eisen-Phosphat-Markt im Laufe des Jahres die gr\u00f6\u00dfte Transaktion Vertrag geboren wurde;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Im Dezember letzten Jahres, Lithium-Quelle neue Energie Lithium-Eisen-Phosphat-Produktionsbasis in Semarang, Indonesien, und die indonesische Investment-Agentur einen Vertrag unterzeichnet, wird Indonesiens Staatsfonds und Co-Investoren 200 Millionen US-Dollar in Investitionen ...... erhalten.<\/li>\n<\/ul>\n\n\n\n<p>\"Eine gute Nachricht nach der anderen ist wirklich ermutigend. Insbesondere die Unterzeichnung des Vertrags mit Zhuhai Guanyu ist zweifellos ein wichtiger Schritt f\u00fcr die globale Ausrichtung von Longpan Technology im Jahr 2025 und gibt der gesamten Li-Power-Industrie einen Schub f\u00fcr die Expansion in \u00dcbersee.\" Chen Xiaoxing, Markendirektor von Lonpac Technology, sagte, dass die erfolgreiche Gestaltung dieses \"Schl\u00fcsselschritts\"<strong>Dank der erfolgreichen Verwirklichung des doppelten Antriebs der \"A+H\"-Aktien.<\/strong><\/p>\n\n\n\n<p><strong>Schreiben des Ministers f\u00fcr ausw\u00e4rtige Angelegenheiten des Vereinigten K\u00f6nigreichs Gro\u00dfbritannien und Nordirland vom 30. Oktober 2024<\/strong><\/p>\n\n\n\n<p><strong>Longbian Technologie<\/strong><\/p>\n\n\n\n<p><strong>Notierung am Main Board der B\u00f6rse von Hongkong<\/strong><\/p>\n\n\n\n<p><strong>Anf\u00e4ngliche Finanzierung von 550 Millionen HK$<\/strong><\/p>\n\n\n\n<p>Dies ist auch seine Landung im April 2017 nach der A-Aktien, wieder in den Kapitalmarkt, werden die einzige \"A + H\" b\u00f6rsennotierten Unternehmen der Stadt, die einzige \"A + H\" b\u00f6rsennotierten Unternehmen der Stadt.<strong>Es ist auch das erste \"A+H\" b\u00f6rsennotierte Unternehmen in der inl\u00e4ndischen Batteriematerialindustrie.<\/strong><\/p>\n\n\n\n<p>\"Die duale Finanzierungsplattform 'A+H' schafft nicht nur einen Finanzierungskanal f\u00fcr Unternehmen, um in- und ausl\u00e4ndisches Kapital zu erweitern, sondern zieht auch die Aufmerksamkeit von mehr internationalen Investoren auf sich, was dazu beitr\u00e4gt, die Sichtbarkeit und das internationale Image von Unternehmen zu verbessern und das Tempo ihrer Globalisierung zu beschleunigen\". Chen Xiaoxing erkl\u00e4rte, dass<strong>Indonesien Lithium-Eisen-Phosphat-Produktion Basis von 30.000 Tonnen Kapazit\u00e4t in der ersten Phase abgeschlossen ist, das erste Quartal dieses Jahres, die zweite Phase von 90.000 Tonnen Kapazit\u00e4t Bau wird offiziell gestartet werden.<\/strong>Gleichzeitig steigt auch die Zahl der f\u00fchrenden Unternehmen der Branche, die an einer langfristigen strategischen Zusammenarbeit mit dem Unternehmen interessiert sind. \"In Zukunft wird Longpan Technology in China ans\u00e4ssig sein und global ausstrahlen, um gr\u00fcne, wertsch\u00f6pfende und vielf\u00e4ltige Kernmateriall\u00f6sungen f\u00fcr die globale kohlenstoffarme Energiewende zu schaffen, die zu einer innovativeren kinetischen Energie von Nanjings neuer Qualit\u00e4tsproduktivit\u00e4t beitragen.\"<strong>0<\/strong><strong>2<\/strong><\/p>\n\n\n\n<p><strong>Dreimal aufgelistet<\/strong><\/p>\n\n\n\n<p><strong>Die Wirtschafts- und Technologieentwicklungszone Nanjing war im vergangenen Jahr die erste in der Stadt, was die Zahl der b\u00f6rsennotierten Unternehmen angeht.<\/strong>Longpan Technology ist das dritte in Hongkong b\u00f6rsennotierte Unternehmen in der Nanjing Economic and Technological Development Zone (NEDZ) in diesem Jahr und das sechste in den letzten zwei Jahren, nach Going Out und Shenghe Biologicals.<strong>Der Park steht an erster Stelle in der Stadt, was die Anzahl der im GJ2024 notierten Unternehmen angeht.<\/strong><\/p>\n\n\n\n<p>Schreiben vom 24. April 2024 des St\u00e4ndigen Vertreters von<\/p>\n\n\n\n<p><strong>Gehen Sie hinaus und fragen Sie.<\/strong><\/p>\n\n\n\n<p><strong>Erfolgreiche Notierung am Main Board der B\u00f6rse von Hongkong<\/strong><\/p>\n\n\n\n<p><strong>\u00dcber 300 Millionen HK$ beim B\u00f6rsengang eingenommen<\/strong><\/p>\n\n\n\n<p><strong>Die erste AIGC-Aktie\" auf dem Hongkonger Aktienmarkt<\/strong><\/p>\n\n\n\n<p>(AIGC, d.h. unter Verwendung von Technologien der k\u00fcnstlichen Intelligenz)<\/p>\n\n\n\n<p>(um Inhalte zu generieren)<\/p>\n\n\n\n<p>Geburtsdatum und -ort: 24. Mai desselben Jahres<\/p>\n\n\n\n<p><strong>Shenghe Biologisch<\/strong><\/p>\n\n\n\n<p><strong>entschied sich ebenfalls f\u00fcr eine Notierung am Main Board der B\u00f6rse von Hongkong<\/strong><\/p>\n\n\n\n<p><strong>461 Millionen HK$ beim B\u00f6rsengang eingenommen<\/strong><\/p>\n\n\n\n<p>Erfolgreiche Landung an der Hongkonger B\u00f6rse<\/p>\n\n\n\n<p>Kennzeichnung Shenghe Biologisch<\/p>\n\n\n\n<p>Werden Sie ein Antik\u00f6rper-Zytokin-Feld<\/p>\n\n\n\n<p>Erstes Unternehmen, das an der B\u00f6rse von Hongkong notiert wird<\/p>\n\n\n\n<p>\"Ein Unternehmen, das Produkte herstellt, sollte die wirklichen Bed\u00fcrfnisse der Nutzer erkennen und zum Kern des Gesch\u00e4fts zur\u00fcckkehren. Nehmen Sie 'Magic Voice Workshop' als Beispiel: Von der Unterst\u00fctzung der Medien bei der L\u00f6sung des Problems des Lesens von Nachrichten bis hin zu einem Tool f\u00fcr die Synchronisation von H\u00f6rb\u00fcchern und schlie\u00dflich der Erschlie\u00dfung der Bed\u00fcrfnisse von Kurzvideo-Erstellern haben wir die heutige KI-Kurzvideo-Synchronisationsplattform entwickelt, die das gesamte Internet im Sturm erobert hat. In diesem Prozess hat uns der Kapitalmarkt weitere Abk\u00fcrzungen erm\u00f6glicht. Li Wei, Director of Public Affairs, sagte: \"Der Eintritt in den Kapitalmarkt ist wie das Einsetzen von \"Fl\u00fcgeln\" f\u00fcr die Entwicklung des Unternehmens, um abzuheben.<\/p>\n\n\n\n<p><strong>Derzeit AIGC<\/strong><\/p>\n\n\n\n<p><strong>\u00dcber 10 Millionen registrierte Nutzer<\/strong><\/p>\n\n\n\n<p><strong>\u00dcber 1 Million bezahlte Abonnenten<\/strong><\/p>\n\n\n\n<p><strong>Die kumulierte Zahl der bedienten Nutzer erreicht mehr als 15 Millionen Menschen<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160257-1024x683.jpg\" alt=\"\" class=\"wp-image-11847\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160257-1024x683.jpg 1024w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160257-300x200.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160257-768x512.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160257-18x12.jpg 18w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160257.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Der zust\u00e4ndige Mitarbeiter des Wirtschaftsentwicklungsb\u00fcros der Wirtschaftsentwicklungszone Nanjing erkl\u00e4rte: \"In den letzten Jahren hat die Wirtschaftsentwicklungszone Nanjing die B\u00f6rsennotierung von Unternehmen als eine ihrer wichtigsten Aufgaben angesehen, die es weiter zu f\u00f6rdern gilt.<strong>Gegenw\u00e4rtig sind 16 in- und ausl\u00e4ndische b\u00f6rsennotierte Unternehmen darin vertreten.<\/strong>\"<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Was den Wertpapiermarkt betrifft, so sind 16 Unternehmen am inl\u00e4ndischen Main Board, an der GEM, der KEM und der HKSE notiert, was fast 10% der Gesamtzahl der b\u00f6rsennotierten Unternehmen in der Stadt ausmacht;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Von der Zeit Dimension, in den letzten 10 Jahren, Nanjing Economic Development Zone hat sich 11 b\u00f6rsennotierten Unternehmen, vor allem in den letzten vier Jahren, die sich auf die neue Notierung von acht;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Was den Umfang der Finanzierung betrifft, so belief sich der Umfang der Eigenkapitalfinanzierung b\u00f6rsennotierter Unternehmen im Park in den vergangenen Jahren auf 27,56 Mrd. RMB, wovon 9,63 Mrd. RMB durch B\u00f6rseng\u00e4nge finanziert wurden und 18,68 Mrd. RMB durch zus\u00e4tzliche Emissionen, Aktienplatzierungen, Wandelanleihen usw. refinanziert wurden, so dass die Finanzierungsfunktion des Kapitalmarkts voll genutzt werden kann.<\/li>\n<\/ul>\n\n\n\n<p>In den letzten Jahren hat die Nanjing Economic Development Zone die Unternehmen des Parks aktiv angeleitet und gef\u00f6rdert, um die Nord-B\u00f6rse, das Science and Technology Innovation Board, die Hongkong-B\u00f6rse und andere Kapitalmarktzugangs- und Entwicklungsm\u00f6glichkeiten zu nutzen, um alle Arten von Unternehmen in der Zone mit fairen, effizienten und qualitativ hochwertigen Finanzdienstleistungen zu versorgen, die die Entwicklung der Energiespeicherkraft auf hohem Niveau vorantreiben.<\/p>\n\n\n\n<p>\"In der n\u00e4chsten Phase wird der offene Bereich den Kapitalmarkt in vollem Umfang nutzen, um die Funktion der Realwirtschaft zu erf\u00fcllen, um mehr Unternehmen zu f\u00f6rdern, die an die B\u00f6rse gehen, um Geldmittel zu beschaffen, und um danach zu streben, sich in der gesamten Bandbreite der Pekinger B\u00f6rse, der Hongkonger B\u00f6rse und der New Yorker B\u00f6rse zu entfalten, und die Zahl der neuen b\u00f6rsennotierten Unternehmen wird weiterhin an der Spitze des Vorstands der Stadt stehen\". sagte der zust\u00e4ndige Verantwortliche.<strong>0<\/strong><strong>3<\/strong><\/p>\n\n\n\n<p><strong>Gradientenzucht<\/strong><\/p>\n\n\n\n<p><strong>F\u00f6rderung der hochwertigen Entwicklung des Kapitalmarktes \"Nanjing Plate\".<\/strong><\/p>\n\n\n\n<p>Schreiben vom 28. Februar 2024 des St\u00e4ndigen Vertreters von<\/p>\n\n\n\n<p>Der Kapitalmarkt \"Nanjing Platte\" starken Gong<\/p>\n\n\n\n<p><strong>Nanjing Kent Composite Material Co.<\/strong><\/p>\n\n\n\n<p><strong>Offiziell auf dem Growth Enterprise Market (GEM) gelandet<\/strong><\/p>\n\n\n\n<p><strong>Der Tag begann mit 80 $.<\/strong><\/p>\n\n\n\n<p><strong>Bis zu 311,73% \u00fcber dem Ausgabepreis<\/strong><\/p>\n\n\n\n<p>Auflistung der Kent-Aktien<\/p>\n\n\n\n<p>Zweifelsohne der Kapitalmarkt f\u00fcr das Jahr 2024<\/p>\n\n\n\n<p>Durchdrungen von der Vitalit\u00e4t Nanjings<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Was die Gesamtmarktkapitalisierung der b\u00f6rsennotierten Unternehmen betrifft, so haben die Unternehmen in Ning j\u00e4hrlich einen \"hervorragenden Antwortbogen\" vorgelegt. Jiangsu Provincial Listed Companies Association ver\u00f6ffentlichte vor kurzem die 2024 Dezember Mitglied Informationen monatlichen Bericht zeigt, dass in den gesamten Marktwert der b\u00f6rsennotierten Unternehmen, wie das Ende des letzten Jahres, der Provinz 696 A-Aktie b\u00f6rsennotierten Unternehmen mit einem Gesamtmarktwert von 6,496 Billionen Yuan.<strong>Unter den sieben b\u00f6rsennotierten Unternehmen mit einer Gesamtmarktkapitalisierung von \u00fcber 100 Milliarden Yuan nimmt Nanjing vier Pl\u00e4tze ein, n\u00e4mlich Guodian Nanrui, Bank of Jiangsu, Huatai Securities und Bank of Nanjing mit einer Gesamtmarktkapitalisierung von 202,588 Milliarden Yuan, 180,210 Milliarden Yuan, 128,552 Milliarden Yuan bzw. 117,500 Milliarden Yuan.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>In Bezug auf die inl\u00e4ndischen und ausl\u00e4ndischen Kapitalmarkt Verkn\u00fcpfung, Nanjing b\u00f6rsennotierten Unternehmen sind auch aktiv. Nach Longpan Technology zu erreichen \"A + H\"-Aktien doppelte Fahrt, im November letzten Jahres, die Wissenschaft und Innovation Bord aufgef\u00fchrt Ningbo Unternehmen ASIC Sicherheit Erwerb von Hongkong-notierten ASIC-Technologie und die Lieferung von Eigenkapital, werden die Wissenschaft und Innovation Bord \"A erhielt H\" gro\u00dfen Verm\u00f6genswert Umstrukturierung Landung der ersten Single, die Fusion und \u00dcbernahme von \"kleinen und gro\u00dfen\". Diese Fusion und \u00dcbernahme verwirklicht \"klein und gro\u00df\".<strong>Nach dem Zusammenschluss und der \u00dcbernahme wird der Umsatz von AsiaInfo Security voraussichtlich mehr als 10 Milliarden Yuan betragen und damit zu einem echten Marktf\u00fchrer auf dem Gebiet der Netzwerksicherheit werden.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>\"Die Verkn\u00fcpfung in- und ausl\u00e4ndischer Kapitalm\u00e4rkte hilft b\u00f6rsennotierten Unternehmen, ihre Finanzierungskan\u00e4le zu erweitern, die Funktion von Fusionen und \u00dcbernahmen sowie Umstrukturierungen wahrzunehmen, die Umwandlung und Entwicklung des Unternehmens zu unterst\u00fctzen, die internationale Wettbewerbsf\u00e4higkeit und den Einfluss der Marke zu steigern und der Entwicklung des Kapitalmarktes 'Nanjing Plate' neue Impulse zu verleihen.\" Jiang Zhaoyi, Vizepr\u00e4sident des Jiangsu Financial Research Institute, sagte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"435\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160300-1024x435.jpg\" alt=\"\" class=\"wp-image-11848\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160300-1024x435.jpg 1024w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160300-300x127.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160300-768x326.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160300-18x8.jpg 18w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160300.jpg 1158w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong><em>Wie kann der Kapitalmarkt \"Nanjing Plate\" besser wachsen?<\/em><\/strong><\/p>\n\n\n\n<p>Nach Meinung von Jiang Zhaoyi, vor allem auf der Grundlage seiner eigenen hochwertigen industriellen Grundlage, wie Software, Smart Grid und anderen Branchen, weiterhin die industriellen Vorteile zu verst\u00e4rken, und f\u00f6rdern mehr f\u00fchrende Unternehmen auf dem Kapitalmarkt zu betreten. Dar\u00fcber hinaus hat Nanjing Zijinshan Laboratory und einzigartige wissenschaftliche und p\u00e4dagogische Vorteile, kann auf den Aufbau von strategischen aufstrebenden Industrien und Zukunftsbranchen durch die Entwicklung von Wissenschaft und Innovation Industrie \u00f6kologische Umfeld vertreten konzentrieren, durch die Anziehungskraft dieser Unternehmen, um die Rahmenbedingungen f\u00fcr die Wirtschaft zu optimieren, so dass die Kultivierung von mehr b\u00f6rsennotierten Unternehmen Ziel.<\/p>\n\n\n\n<p>Municipal Party Committee Financial Office ergab, dass im Jahr 2025, Nanjing wird im Einklang mit dem Gradienten Anbau des Unternehmens die Arbeit Ideen, Klassifizierung Politik, pr\u00e4zise Unterst\u00fctzung, und die Bem\u00fchungen um die Unternehmen b\u00f6rsennotierten Service, Service b\u00f6rsennotierten Unternehmen, und zur F\u00f6rderung der Kapitalmarkt \"Nanjing Platte\" hochwertige Entwicklung.<\/p>","protected":false},"excerpt":{"rendered":"<p>Von der Landung von Kent an der GEM-Tafel als erstes b\u00f6rsennotiertes Unternehmen in Ningbo in jenem Jahr \u00fcber die Notierung von Door Ask und Shenghe Biologicals an der Haupttafel der B\u00f6rse von Hongkong einen Monat nacheinander bis hin zur Notierung an der Haupttafel der B\u00f6rse von Shanghai [...].<\/p>","protected":false},"author":2,"featured_media":11846,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[85,16],"tags":[],"class_list":["post-11845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zheng_fu_zheng_ce","category-incubation_information"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u80a1\u5e02\u91cc\u7684\u5357\u4eac\u677f\u5757 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tigerandtech.com\/de\/gu_shi_li_de_nan_jing_ban_kuai\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u80a1\u5e02\u91cc\u7684\u5357\u4eac\u677f\u5757 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"og:description\" content=\"\u4ece\u80af\u7279\u80a1\u4efd\u767b\u9646\u521b\u4e1a\u677f\u6210\u4e3a\u5f53\u5e74\u9996\u5bb6\u4e0a\u5e02\u5b81\u4f01\uff0c\u5230\u51fa\u95e8\u95ee\u95ee\u548c\u76db\u79be\u751f\u7269\u95f4\u9694\u4e00\u4e2a\u6708\u5148\u540e\u5728\u6e2f\u4ea4\u6240\u4e3b\u677f\u4e0a\u5e02\uff0c\u518d\u5230\u4e0a\u4ea4\u6240\u4e3b\u677f\u4e0a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tigerandtech.com\/de\/gu_shi_li_de_nan_jing_ban_kuai\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-08T08:04:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-08T08:04:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tiger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tiger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/\"},\"author\":{\"name\":\"Tiger\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880\"},\"headline\":\"\u80a1\u5e02\u91cc\u7684\u5357\u4eac\u677f\u5757\",\"datePublished\":\"2025-01-08T08:04:48+00:00\",\"dateModified\":\"2025-01-08T08:04:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/\"},\"wordCount\":25,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg\",\"articleSection\":[\"\u5b98\u65b9\u884c\u52a8\",\"\u8d44\u8baf\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/\",\"url\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/\",\"name\":\"\u80a1\u5e02\u91cc\u7684\u5357\u4eac\u677f\u5757 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"isPartOf\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg\",\"datePublished\":\"2025-01-08T08:04:48+00:00\",\"dateModified\":\"2025-01-08T08:04:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#primaryimage\",\"url\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg\",\"contentUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.tigerandtech.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u80a1\u5e02\u91cc\u7684\u5357\u4eac\u677f\u5757\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#website\",\"url\":\"https:\/\/www.tigerandtech.com\/de\/\",\"name\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tigerandtech.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\",\"name\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"url\":\"https:\/\/www.tigerandtech.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp\",\"contentUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp\",\"width\":1003,\"height\":116,\"caption\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880\",\"name\":\"Tiger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g\",\"caption\":\"Tiger\"},\"url\":\"https:\/\/www.tigerandtech.com\/de\/author\/tiger\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nanjing Board auf dem Aktienmarkt - Jiangsu Xiaohu Technology Development Co.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tigerandtech.com\/de\/gu_shi_li_de_nan_jing_ban_kuai\/","og_locale":"de_DE","og_type":"article","og_title":"\u80a1\u5e02\u91cc\u7684\u5357\u4eac\u677f\u5757 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8","og_description":"\u4ece\u80af\u7279\u80a1\u4efd\u767b\u9646\u521b\u4e1a\u677f\u6210\u4e3a\u5f53\u5e74\u9996\u5bb6\u4e0a\u5e02\u5b81\u4f01\uff0c\u5230\u51fa\u95e8\u95ee\u95ee\u548c\u76db\u79be\u751f\u7269\u95f4\u9694\u4e00\u4e2a\u6708\u5148\u540e\u5728\u6e2f\u4ea4\u6240\u4e3b\u677f\u4e0a\u5e02\uff0c\u518d\u5230\u4e0a\u4ea4\u6240\u4e3b\u677f\u4e0a [&hellip;]","og_url":"https:\/\/www.tigerandtech.com\/de\/gu_shi_li_de_nan_jing_ban_kuai\/","og_site_name":"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8","article_published_time":"2025-01-08T08:04:48+00:00","article_modified_time":"2025-01-08T08:04:51+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg","type":"image\/jpeg"}],"author":"Tiger","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tiger","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#article","isPartOf":{"@id":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/"},"author":{"name":"Tiger","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880"},"headline":"\u80a1\u5e02\u91cc\u7684\u5357\u4eac\u677f\u5757","datePublished":"2025-01-08T08:04:48+00:00","dateModified":"2025-01-08T08:04:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/"},"wordCount":25,"commentCount":0,"publisher":{"@id":"https:\/\/www.tigerandtech.com\/de\/#organization"},"image":{"@id":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg","articleSection":["\u5b98\u65b9\u884c\u52a8","\u8d44\u8baf"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/","url":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/","name":"Nanjing Board auf dem Aktienmarkt - Jiangsu Xiaohu Technology Development Co.","isPartOf":{"@id":"https:\/\/www.tigerandtech.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#primaryimage"},"image":{"@id":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg","datePublished":"2025-01-08T08:04:48+00:00","dateModified":"2025-01-08T08:04:51+00:00","breadcrumb":{"@id":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#primaryimage","url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg","contentUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250108160243.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.tigerandtech.com\/gu_shi_li_de_nan_jing_ban_kuai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.tigerandtech.com\/"},{"@type":"ListItem","position":2,"name":"\u80a1\u5e02\u91cc\u7684\u5357\u4eac\u677f\u5757"}]},{"@type":"WebSite","@id":"https:\/\/www.tigerandtech.com\/de\/#website","url":"https:\/\/www.tigerandtech.com\/de\/","name":"Jiangsu Xiaohu Technology Development Co.","description":"","publisher":{"@id":"https:\/\/www.tigerandtech.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tigerandtech.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.tigerandtech.com\/de\/#organization","name":"Jiangsu Xiaohu Technology Development Co.","url":"https:\/\/www.tigerandtech.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp","contentUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp","width":1003,"height":116,"caption":"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8"},"image":{"@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880","name":"Tiger","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g","caption":"Tiger"},"url":"https:\/\/www.tigerandtech.com\/de\/author\/tiger\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts\/11845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/comments?post=11845"}],"version-history":[{"count":0,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts\/11845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/media\/11846"}],"wp:attachment":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/media?parent=11845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/categories?post=11845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/tags?post=11845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}