{"id":12102,"date":"2025-01-21T16:01:01","date_gmt":"2025-01-21T08:01:01","guid":{"rendered":"https:\/\/www.tigerandtech.com\/?p=12102"},"modified":"2025-01-21T16:01:03","modified_gmt":"2025-01-21T08:01:03","slug":"xuan_hao_xin_fang_guo_xin_nian","status":"publish","type":"post","link":"https:\/\/www.tigerandtech.com\/de\/xuan_hao_xin_fang_guo_xin_nian\/","title":{"rendered":"Die Wahl eines neuen Hauses f\u00fcr das neue Jahr"},"content":{"rendered":"<p>Die Schlange springt ins neue Jahr, der Segen versch\u00f6nert das Herz - das Fr\u00fchlingsfest im Jahr der Schlange r\u00fcckt immer n\u00e4her, und die festliche Atmosph\u00e4re des neuen Jahres wird immer st\u00e4rker. K\u00fcrzlich organisierte der Bezirk Gulou das dritte Los der Wohnungslotterie 2024 f\u00fcr \u00f6ffentliche Mietwohnungen (allgemein bekannt als \u00f6ffentliche Mietwohnungen). Am Vorabend des besten traditionellen chinesischen Festes haben 135 Familien ihre eigenen \u00f6ffentlichen Mietwohnungen in Aussicht und streben nach einem besseren Leben.<\/p>\n\n\n\n<p>\"Nach den einschl\u00e4gigen Vorschriften k\u00f6nnen bei der Vergabe von \u00f6ffentlichem Mietwohnraum Gruppen wie Personen, die regelm\u00e4\u00dfige staatliche Rentenzusch\u00fcsse f\u00fcr Privilegierte erhalten, einsame \u00e4ltere Menschen, Behinderte, Personen, die sich durch Mut und Tapferkeit ausgezeichnet haben, vorbildliche Arbeitnehmer und kinderreiche Familien bevorzugt werden. F\u00fcr besondere Objekte mit geistigen Behinderungen und k\u00f6rperlichen Behinderungen, die zu Mobilit\u00e4tsproblemen f\u00fchren, kann bei der Zuteilung von Stockwerken, die ihren tats\u00e4chlichen Bed\u00fcrfnissen entsprechen, Vorrang einger\u00e4umt werden.\" Der Verantwortliche des Wohnsicherheitszentrums des Bezirks Gulou sagte: \"Bei dieser Zimmerverlosung werden neben den Familien mit dem Recht der ersten Wahl auch alle anderen nach der Reihenfolge der Anmeldung zugeteilt, um ein faires und gerechtes Verfahren zu gew\u00e4hrleisten.\"<\/p>\n\n\n\n<p>Die 135 \u00f6ffentlichen Mietwohnungen befinden sich in Huagang, Dingjiazhuang, Mengbei, Baishui und anderen Bezirken und haben alle eine Gr\u00f6\u00dfe von 45-50 Quadratmetern f\u00fcr ein einziges Schlafzimmer. Die Auslosung und Freigabe der Wohnungen ist in Ordnung, und um die Formalit\u00e4ten zu erledigen, freuen sich alle, wenn sie ihr eigenes Wohnungsbest\u00e4tigungsblatt erhalten. Anschlie\u00dfend erhalten sie je nach Verfahren Schl\u00fcssel und ziehen in ihre neuen Wohnungen ein.<\/p>\n\n\n\n<p><strong>Schutz der Menschen und Verwirklichung ihrer Tr\u00e4ume von einem Leben in Frieden und Sicherheit<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160019-1024x683.png\" alt=\"\" class=\"wp-image-12103\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160019-1024x683.png 1024w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160019-300x200.png 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160019-768x512.png 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160019-18x12.png 18w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160019.png 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Es ist der Traum eines jeden Menschen, ein eigenes Haus zu haben.<\/strong><\/p>\n\n\n\n<p>Tante Wu, die 68 Jahre alt ist, sagte: \"Ich wohne derzeit in einem gemieteten Zimmer, das mich etwa 2.000 Yuan pro Monat kostet. Mit den \u00f6ffentlichen Mietwohnungen werden die Ausgaben in diesem Bereich gesenkt und ich werde bequemer leben, was eine L\u00f6sung f\u00fcr meine Sorgen ist.<\/p>\n\n\n\n<p>Herr Qian, 55, mietet derzeit ein Zimmer im Haus eines Freundes, was ung\u00fcnstig ist, da er nur ein Zimmer hat. Mit den \u00f6ffentlichen Mietwohnungen werde ich meinen eigenen, unabh\u00e4ngigen Raum haben, und die Qualit\u00e4t meines Lebens wird sich erheblich verbessern\", sagte er. Au\u00dferdem sind die Wohnungen leicht zu erreichen, da Busse und U-Bahnen in der N\u00e4he halten, was es mir erleichtert, mich um meine Mutter zu k\u00fcmmern.<\/p>\n\n\n\n<p>\"\u00d6ffentliche Mietwohnungen werden von der Regierung investiert, um zu bauen (erh\u00f6hen) oder bieten politische Unterst\u00fctzung, begrenzt auf die Haushaltsgr\u00f6\u00dfe und Mietniveau, die Bereitstellung der Sicherheit Objekt Mietsicherheit Geh\u00e4use.\" Der zust\u00e4ndige Mitarbeiter des Gulou District Real Estate Bureau sagte: \"\u00d6ffentliche Mietwohnungen werden in \u00dcbereinstimmung mit der Kombination aus Mietreduzierung und der Trennung von Miete und Subventionierung des Mietmanagements umgesetzt, um die Wohnsicherheit zu st\u00e4rken und unser Bestes zu tun, damit jeder in einem Ort des Wohnens und des Seelenfriedens leben kann. Gleichzeitig gew\u00e4hrleisten wir den Grundsatz der Priorit\u00e4t bei der Vergabe von Wohnungen und halten uns strikt an die Melde- und Pr\u00fcfverfahren, was die Anerkennung der Bewerberfamilien gewonnen hat.\"<\/p>\n\n\n\n<p>In den kalten Wintermonaten, im alten und im neuen Jahr, wenn das Neujahrsfest vor der T\u00fcr steht, haben sich im Bezirk Gulou 135 Familien f\u00fcr ein neues Haus entschieden und kommen in den Genuss der staatlichen Wohnsicherheit, was das Gl\u00fccksgef\u00fchl und die Erfolgserlebnisse erheblich steigert.<\/p>","protected":false},"excerpt":{"rendered":"<p>Geistige Schlange springt ins neue Jahr, Segen versch\u00f6nert das Herz - das Fr\u00fchlingsfest des Jahres der Schlange im Jahr der Schlange in B Si r\u00fcckt immer n\u00e4her, und die festliche Atmosph\u00e4re des neuen Jahres wird immer st\u00e4rker. K\u00fcrzlich organisierte der Bezirk Gulou das 2024. [...]...<\/p>","protected":false},"author":2,"featured_media":12104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u9009\u597d\u65b0\u623f\u8fc7\u65b0\u5e74 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tigerandtech.com\/de\/xuan_hao_xin_fang_guo_xin_nian\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u9009\u597d\u65b0\u623f\u8fc7\u65b0\u5e74 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"og:description\" content=\"\u7075\u86c7\u8dc3\u65b0\u6625\uff0c\u798f\u6cfd\u6da6\u5fc3\u7530\u2014\u2014\u4e59\u5df3\u86c7\u5e74\u6625\u8282\u7684\u811a\u6b65\u8d8a\u6765\u8d8a\u8fd1\uff0c\u8fc7\u5e74\u7684\u559c\u5e86\u6c1b\u56f4\u65e5\u76ca\u6d53\u539a\u3002\u8fd1\u65e5\uff0c\u9f13\u697c\u533a\u7ec4\u7ec7\u5f00\u5c552024\u5e74\u7b2c [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tigerandtech.com\/de\/xuan_hao_xin_fang_guo_xin_nian\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T08:01:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-21T08:01:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tiger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tiger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/\"},\"author\":{\"name\":\"Tiger\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880\"},\"headline\":\"\u9009\u597d\u65b0\u623f\u8fc7\u65b0\u5e74\",\"datePublished\":\"2025-01-21T08:01:01+00:00\",\"dateModified\":\"2025-01-21T08:01:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160024.jpg\",\"articleSection\":[\"\u672a\u5206\u7c7b\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/\",\"url\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/\",\"name\":\"\u9009\u597d\u65b0\u623f\u8fc7\u65b0\u5e74 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"isPartOf\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160024.jpg\",\"datePublished\":\"2025-01-21T08:01:01+00:00\",\"dateModified\":\"2025-01-21T08:01:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#primaryimage\",\"url\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160024.jpg\",\"contentUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160024.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.tigerandtech.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u9009\u597d\u65b0\u623f\u8fc7\u65b0\u5e74\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#website\",\"url\":\"https:\/\/www.tigerandtech.com\/de\/\",\"name\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tigerandtech.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\",\"name\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"url\":\"https:\/\/www.tigerandtech.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp\",\"contentUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp\",\"width\":1003,\"height\":116,\"caption\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880\",\"name\":\"Tiger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g\",\"caption\":\"Tiger\"},\"url\":\"https:\/\/www.tigerandtech.com\/de\/author\/tiger\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"W\u00e4hlen Sie ein neues Haus f\u00fcr das neue Jahr - Jiangsu Xiaohu Science &amp; Technology Development Co.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tigerandtech.com\/de\/xuan_hao_xin_fang_guo_xin_nian\/","og_locale":"de_DE","og_type":"article","og_title":"\u9009\u597d\u65b0\u623f\u8fc7\u65b0\u5e74 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8","og_description":"\u7075\u86c7\u8dc3\u65b0\u6625\uff0c\u798f\u6cfd\u6da6\u5fc3\u7530\u2014\u2014\u4e59\u5df3\u86c7\u5e74\u6625\u8282\u7684\u811a\u6b65\u8d8a\u6765\u8d8a\u8fd1\uff0c\u8fc7\u5e74\u7684\u559c\u5e86\u6c1b\u56f4\u65e5\u76ca\u6d53\u539a\u3002\u8fd1\u65e5\uff0c\u9f13\u697c\u533a\u7ec4\u7ec7\u5f00\u5c552024\u5e74\u7b2c [&hellip;]","og_url":"https:\/\/www.tigerandtech.com\/de\/xuan_hao_xin_fang_guo_xin_nian\/","og_site_name":"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8","article_published_time":"2025-01-21T08:01:01+00:00","article_modified_time":"2025-01-21T08:01:03+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160024.jpg","type":"image\/jpeg"}],"author":"Tiger","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tiger","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#article","isPartOf":{"@id":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/"},"author":{"name":"Tiger","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880"},"headline":"\u9009\u597d\u65b0\u623f\u8fc7\u65b0\u5e74","datePublished":"2025-01-21T08:01:01+00:00","dateModified":"2025-01-21T08:01:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/www.tigerandtech.com\/de\/#organization"},"image":{"@id":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160024.jpg","articleSection":["\u672a\u5206\u7c7b"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/","url":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/","name":"W\u00e4hlen Sie ein neues Haus f\u00fcr das neue Jahr - Jiangsu Xiaohu Science &amp; Technology Development Co.","isPartOf":{"@id":"https:\/\/www.tigerandtech.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#primaryimage"},"image":{"@id":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160024.jpg","datePublished":"2025-01-21T08:01:01+00:00","dateModified":"2025-01-21T08:01:03+00:00","breadcrumb":{"@id":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#primaryimage","url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160024.jpg","contentUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/01\/Weixin-Image_20250121160024.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.tigerandtech.com\/xuan_hao_xin_fang_guo_xin_nian\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.tigerandtech.com\/"},{"@type":"ListItem","position":2,"name":"\u9009\u597d\u65b0\u623f\u8fc7\u65b0\u5e74"}]},{"@type":"WebSite","@id":"https:\/\/www.tigerandtech.com\/de\/#website","url":"https:\/\/www.tigerandtech.com\/de\/","name":"Jiangsu Xiaohu Technology Development Co.","description":"","publisher":{"@id":"https:\/\/www.tigerandtech.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tigerandtech.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.tigerandtech.com\/de\/#organization","name":"Jiangsu Xiaohu Technology Development Co.","url":"https:\/\/www.tigerandtech.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp","contentUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp","width":1003,"height":116,"caption":"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8"},"image":{"@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880","name":"Tiger","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g","caption":"Tiger"},"url":"https:\/\/www.tigerandtech.com\/de\/author\/tiger\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts\/12102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/comments?post=12102"}],"version-history":[{"count":0,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts\/12102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/media\/12104"}],"wp:attachment":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/media?parent=12102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/categories?post=12102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/tags?post=12102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}