{"id":12718,"date":"2025-03-12T10:54:20","date_gmt":"2025-03-12T02:54:20","guid":{"rendered":"https:\/\/www.tigerandtech.com\/?p=12718"},"modified":"2025-03-12T10:54:23","modified_gmt":"2025-03-12T02:54:23","slug":"sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi","status":"publish","type":"post","link":"https:\/\/www.tigerandtech.com\/de\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/","title":{"rendered":"Biomedizinische Strecke, Nanjing durchbricht seinen Kokon und hebt seine Fl\u00fcgel"},"content":{"rendered":"<p>biomedizinische Industrie<\/p>\n\n\n\n<p>Es ist eines der wichtigsten zukunftsweisenden Industriecluster in Nanjing.<\/p>\n\n\n\n<p>Es ist auch Nanjings Aufbau einer starken Industriestadt,<\/p>\n\n\n\n<p>Hauptsto\u00dfrichtungen der Entwicklung einer neuen qualitativen Produktivit\u00e4t<\/p>\n\n\n\n<p>Vor kurzem hat die st\u00e4dtische Partei Ausschuss Netzwerk Informationsb\u00fcro organisiert die \"Entdeckung von Nanjing\" neue Medien Linie und in die biomedizinische Industrie Netzwerk Thema Interview-Aktivit\u00e4ten, die zentralen und provinziellen wichtigsten Nachrichten Netzwerk Medien, Finanz- neue Medien Interview-Gruppe, bestehend aus mehr als 20 Personen.<strong>Besuch des Nanjing Biomedical Valley, Besichtigung von Forschungs- und Entwicklungslabors, Dialog mit dem technischen Team des Unternehmens, Feldforschung \u00fcber neue Technologien, neue Denkweisen und neue Errungenschaften der biomedizinischen Industrie in Nanjing.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"893\" height=\"402\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/1-1.png\" alt=\"\" class=\"wp-image-12719\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/1-1.png 893w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/1-1-300x135.png 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/1-1-768x346.png 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/1-1-18x8.png 18w\" sizes=\"(max-width: 893px) 100vw, 893px\" \/><\/figure>\n\n\n\n<p>Nanjing ist wieder \"aus dem Rennen\".<\/p>\n\n\n\n<p>Sehen Sie sich das Medien-Spotlight an.<\/p>\n\n\n\n<p>\ud83d\udc47\ud83c\udffb<strong><\/strong><\/p>\n\n\n\n<p><strong>China Jiangsu Netzwerk<br><br>Wie kann Nanjings biomedizinische Industrie den Durchbruch zur 100-Milliarden-Dollar-Schiene schaffen?<\/strong>(Original link: https:\/\/finance.jschina.com.cn\/202503\/t20250306_s67c9487de4b05777c1786f14.shtml)<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"651\" height=\"1024\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/2-14-651x1024.jpg\" alt=\"\" class=\"wp-image-12720\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/2-14-651x1024.jpg 651w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/2-14-191x300.jpg 191w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/2-14-768x1208.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/2-14-976x1536.jpg 976w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/2-14-8x12.jpg 8w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/2-14.jpg 1080w\" sizes=\"(max-width: 651px) 100vw, 651px\" \/><\/figure>\n\n\n\n<p><strong>Surfen Nachrichten sechs Dynastien alten Hauptstadt von Nanjing, wie man \"Hochsprung\", \u00f6ffnen Sie die biomedizinische Industrie neue Muster<\/strong>(Urspr\u00fcnglicher Link: https:\/\/m.thepaper.cn\/newsDetail_forward_30329967)<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"615\" height=\"1024\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/3-11-615x1024.jpg\" alt=\"\" class=\"wp-image-12721\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/3-11-615x1024.jpg 615w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/3-11-180x300.jpg 180w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/3-11-768x1279.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/3-11-922x1536.jpg 922w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/3-11-7x12.jpg 7w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/3-11.jpg 1080w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/figure>\n\n\n\n<p><strong>Niu Ka Video<\/strong><\/p>\n\n\n\n<p><strong>Nanjing Biomedical Valley: Die Welle der Innovation, die \"Cocoon\"-Stra\u00dfe der biomedizinischen Industrie<\/strong>(Urspr\u00fcnglicher Link: http:\/\/m2.nbs.cn\/article\/917805.html?id=917805&amp;mid=1)<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"997\" height=\"1006\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/4-6.jpg\" alt=\"\" class=\"wp-image-12722\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/4-6.jpg 997w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/4-6-297x300.jpg 297w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/4-6-150x150.jpg 150w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/4-6-768x775.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/4-6-12x12.jpg 12w\" sizes=\"(max-width: 997px) 100vw, 997px\" \/><\/figure>\n\n\n\n<p><strong>China Business News Service<\/strong><a href=\"https:\/\/mp.weixin.qq.com\/s?__biz=MzIwMDE5NDM0Mg==&amp;mid=2650818246&amp;idx=1&amp;sn=87f7698244045bfd30f743919f9b45d2&amp;scene=21#wechat_redirect\"><strong>Das Nanjing Treasure Valley ist voll von Experten.<\/strong>(Klicken Sie auf den Sprung-Link)<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"744\" height=\"1024\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/5-5-744x1024.jpg\" alt=\"\" class=\"wp-image-12723\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/5-5-744x1024.jpg 744w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/5-5-218x300.jpg 218w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/5-5-768x1057.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/5-5-9x12.jpg 9w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/5-5.jpg 1080w\" sizes=\"(max-width: 744px) 100vw, 744px\" \/><\/figure>\n\n\n\n<p><strong>Sch\u00f6pferische Kommune<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/mp.weixin.qq.com\/s?__biz=MjM5ODk4NTUzNg==&amp;mid=2665058579&amp;idx=1&amp;sn=417e5546d507d9a3a058e0546eed1ad0&amp;scene=21#wechat_redirect\"><strong>Nehmen Sie die Zulage des Staatsrats! 87 Jahre Hegemonie der R\u00fcckkehrer und sein Einhorn, damit Nanjing eine \"Billionenspur\" aufrei\u00dft!<\/strong>(Klicken Sie auf den Sprung-Link)<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"669\" height=\"1024\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/6-5-669x1024.jpg\" alt=\"\" class=\"wp-image-12724\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/6-5-669x1024.jpg 669w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/6-5-196x300.jpg 196w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/6-5-768x1175.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/6-5-1004x1536.jpg 1004w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/6-5-8x12.jpg 8w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/6-5.jpg 1080w\" sizes=\"(max-width: 669px) 100vw, 669px\" \/><\/figure>\n\n\n\n<p>Folgen Sie dem Stift und der Kamera der Medien<\/p>\n\n\n\n<p>Lassen Sie uns gemeinsam auf Entdeckungsreise gehen.<\/p>\n\n\n\n<p>Nanjing Biomedizinische Industrie<\/p>\n\n\n\n<p>Die Geschichte hinter der Geschichte<\/p>\n\n\n\n<p>\ud83d\udc47<\/p>\n\n\n\n<p><strong>Den \"Code des Lebens\" entschl\u00fcsseln.<\/strong><strong>Pilot-Gentechnik<\/strong><\/p>\n\n\n\n<p>\u25cbGene beeinflussen den Menschen ein Leben lang. Bei der Erforschung von Genen ist die Hilfe von Gentestinstrumenten unerl\u00e4sslich. Gensequenzer erfordern jedoch Chips, Informationsalgorithmen und andere wissenschaftliche und technologische Verfahren mit hohen technischen H\u00fcrden, gro\u00dfen Forschungsinvestitionen und langen Forschungs- und Entwicklungszyklen, und nur eine Handvoll Unternehmen weltweit ist in der Lage, eine Massenproduktion zu erreichen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/7-4-1024x768.jpg\" alt=\"\" class=\"wp-image-12725\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/7-4-1024x768.jpg 1024w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/7-4-300x225.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/7-4-768x576.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/7-4-16x12.jpg 16w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/7-4.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Seit seiner Gr\u00fcndung im Jahr 2012 widmet sich Zenmax Bio der Forschung und Entwicklung von Gensequenzern f\u00fcr den heimischen Markt.<strong>Nach mehreren Jahren technologischer Forschung verf\u00fcgt das Unternehmen \u00fcber das Sequenzierungstechnologiesystem \"SURFSeq\" mit unabh\u00e4ngigen geistigen Eigentumsrechten und hat die unabh\u00e4ngige Kontrolle \u00fcber die gesamte Plattform von \"Instrument, Reagenz, Chip und Software\" realisiert. \"SURFSeq ist einer der wenigen Hersteller von Sequenziersystemen in der Welt, der \u00fcber die vorgelagerte Kerntechnologie der Gensequenzierung und die F\u00e4higkeit zur kommerziellen Bereitstellung verf\u00fcgt.<\/strong><\/p>\n\n\n\n<p>Die Beziehung zwischen Gensequenzierern und Testchips \u00e4hnelt der von Druckern und Tintenpatronen, wobei der Chip als Hightech-Verbrauchsmaterial Wissen aus verschiedenen Disziplinen wie Physik, Chemie und Biologie enth\u00e4lt\". Zhou Zhiliang, Gesch\u00e4ftsf\u00fchrer von Nanjing Zenmax Bio, nutzte die Analogie zwischen einem Drucker und einer Tintenpatrone, um die Prinzipien und Funktionen von Gensequenzern anschaulich zu erl\u00e4utern. \"Wir haben vor drei Jahren begonnen, den \u00dcberseemarkt zu erschlie\u00dfen, und der Umsatz auf dem \u00dcberseemarkt entspricht inzwischen dem des Inlandsmarktes. W\u00e4hrend wir den Markt ausbauen, aktualisieren wir st\u00e4ndig unsere Produkte, und unsere Multi-Gradienten-Produktarrays k\u00f6nnen die Anforderungen von wissenschaftlichen Forschungsinstituten, Gesundheitsorganisationen und industriellen Anwendern an die Sequenzierung umfassend erf\u00fcllen und die wissenschaftliche Spitzenforschung und Pr\u00e4zisionsmedizin unterst\u00fctzen.\"<\/p>\n\n\n\n<p>Im Biomedical Valley von Nanjings Jiangbei New District hat sich ein weiteres Pharmaunternehmen als bahnbrechende Innovation erwiesen.<\/p>\n\n\n\n<p>Fr\u00fcherkennung, Fr\u00fchdiagnose und Fr\u00fchbehandlung\" gilt derzeit als die wirksamste Strategie zur Krebsbek\u00e4mpfung. Das von Shiho Genetics unabh\u00e4ngig entwickelte Krebsfr\u00fcherkennungsprodukt \"Shiho Hawkeye\" kann neun Krebsarten untersuchen, darunter Lungen-, Leber-, Magen-, Prostata-, Brust-, Speiser\u00f6hren-, Geb\u00e4rmutter- und Bauchspeicheldr\u00fcsenkrebs, und die L\u00e4sion in einem einzigen Test mit nur einer Blutprobe lokalisieren.<strong>Es ist eines der vier einzigen Krebsfr\u00fcherkennungsprodukte der Welt, die von der FDA eine bahnbrechende Zulassung erhalten haben, und seine Technologie hat das weltweit f\u00fchrende Niveau erreicht.<\/strong><\/p>\n\n\n\n<p>Im Oktober 2023 erhielt das von Shiho Genetics unabh\u00e4ngig entwickelte Shiho One NGS Large Panel Kit von der staatlichen Arzneimittelbeh\u00f6rde die Genehmigung f\u00fcr die Vermarktung innovativer Medizinprodukte.<strong>Wurde das erste und derzeit einzige Tumor-NGS-Gro\u00dfpanel (Genkombination) in China.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/8-1-1024x576.png\" alt=\"\" class=\"wp-image-12726\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/8-1-1024x576.png 1024w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/8-1-300x169.png 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/8-1-768x432.png 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/8-1-18x10.png 18w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/8-1.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Shiho Genetics hat sich seit mehr als 10 Jahren intensiv mit onkologischen Pr\u00e4zisionstests befasst. Mit einem Testvolumen von Millionen von Proben und einer hohen F&amp;E-Investitionsquote hat sich das Unternehmen kontinuierlich an die Spitze des inl\u00e4ndischen Marktanteils f\u00fcr onkologische NGS-Tests gesetzt. Als onkologisches Medizinunternehmen, das im Nanjing Jiangbei New District kultiviert wurde und gewachsen ist, hat Shiho Genetics mit vielen Universit\u00e4ten und Forschungsinstituten in Nanjing Industrie-Akademie-Forschungsbasen aufgebaut und Talente aus verschiedenen Disziplinen wie Biologie und k\u00fcnstlicher Intelligenz rekrutiert, und gleichzeitig mit der Nanjing Medical University und der Southeast University zusammengearbeitet, um gemeinsam Talente zu f\u00f6rdern.<\/p>\n\n\n\n<p><strong>Durchbruch bei der Innovation, vom lokalen zum globalen Wettbewerb<\/strong><strong><\/strong><\/p>\n\n\n\n<p>\u25cb In Nanjing sind innovative Arzneimittel im Ausland auf dem Vormarsch.<\/p>\n\n\n\n<p>Ende letzten Jahres wurde ein Patient aus Hongkong mit einem innovativen Medikament von Reindeer Biologicals, einem Unternehmen in der Jiangbei New Area, behandelt - dem CAR-T-Zellprodukt Igibi Orensei Injection (FUCASO). Bei der Behandlung des ersten Patienten aus Hongkong \u00fcberwachten der Zoll von Nanjing und die Jiangbei New Area gemeinsam den Mechanismus zur \u00dcberwindung des Engpasses in der grenz\u00fcberschreitenden Logistik, so dass der Transport der Blutproben des Patienten aus Hongkong nach Nanjing und der Beginn der Vorbereitung innerhalb von 48 Stunden abgeschlossen werden konnten.<\/p>\n\n\n\n<p>Im Gegensatz zu herk\u00f6mmlichen Medikamenten und Behandlungen handelt es sich bei dieser Therapie um Chinas erste selbst entwickelte und vollst\u00e4ndig prozessunabh\u00e4ngige Produktion, die auf den Patienten zugeschnitten ist. Konkret werden damit h\u00e4matologische Malignome behandelt, indem T-Zellen aus dem Blut des Patienten entnommen, im Labor umgewandelt und dann als Infusion in den K\u00f6rper zur\u00fcckgef\u00fchrt werden.<\/p>\n\n\n\n<p>Lin Menghan, Sekret\u00e4r des Verwaltungsrats von Reindeer Biologicals, sagte, dass das innovative Medikament seit seiner Zulassung durch die staatliche Arzneimittelbeh\u00f6rde im Juni 2023 Hunderten von Patienten zugute gekommen sei.<strong>Reindeer Biologics, das in Nanjing produziert und aus \u00dcbersee beliefert wird, hat mit einer Reihe von Organisationen zusammengearbeitet, um Zelltherapie-Medikamente zu f\u00f6rdern, die nach \u00dcbersee gehen, und hat aktiv das Modell der Anwerbung von Patienten aus \u00dcbersee erforscht. Die Erforschung dieses innovativen Modells und die hervorragenden klinischen Ergebnisse haben dazu gef\u00fchrt, dass mehr als 20 Patienten aus Europa, Afrika, S\u00fcdostasien und anderen L\u00e4ndern zur Behandlung nach China gekommen sind.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg\" alt=\"\" class=\"wp-image-12727\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg 800w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1-300x225.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1-768x576.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>\u25cb \"Die Ger\u00e4te werden immer kleiner und immer leistungsf\u00e4higer.\" Das im Jahr 2000 in Nanjing gegr\u00fcndete Unternehmen Nanwei Medical befasst sich haupts\u00e4chlich mit der Forschung, Entwicklung, Produktion und dem Vertrieb von minimal-invasiven medizinischen Ger\u00e4ten und Verbrauchsmaterialien. Als Pionier der inl\u00e4ndischen Substitution verf\u00fcgt die 2015 eingef\u00fchrte \"Harmony Clamp\" \u00fcber eine 360-Grad-Pr\u00e4zisionsklemmung mit einer gleitenden Rillenstruktur, und der Preis betr\u00e4gt nur 1\/8 der importierten \u00e4hnlichen Produkte, wodurch das Monopol ausl\u00e4ndischer Marken beendet wird und der j\u00e4hrliche Produktionswert eines einzelnen Produkts Hunderte von Millionen Yuan erreicht. Seitdem kann das innovative Produkt \"Einweg-Choledochoskop\" tief in den Gallengang eindringen, um eine hochaufl\u00f6sende Darstellung der Gallenwege und eine minimalinvasive endoskopische Diagnose und Behandlung zu erm\u00f6glichen.<\/p>\n\n\n\n<p>Laut Li Changqing, Executive President von Nanwei Medical, hat das Unternehmen landesweit mehr als 6.000 Krankenh\u00e4user beliefert, darunter mehr als 55%-Terti\u00e4rkliniken, und ist zu einem f\u00fchrenden Unternehmen in der heimischen Branche f\u00fcr minimalinvasive medizinische Ger\u00e4te geworden. Der Auslandsmarkt ist ebenfalls das Ziel von Nanwei Medical. \"Heute k\u00f6nnen die Produkte und Dienstleistungen des Unternehmens mehr als 90 L\u00e4nder und Regionen erreichen, und das Unternehmen wird auch in Zukunft mit Innovationen f\u00fchrend sein.\"<\/p>\n\n\n\n<p><strong>Vom einzelnen Durchbruch zur kettenweiten Synergie<\/strong><\/p>\n\n\n\n<p><strong>Stetige Zunahme von \u00f6kologischen Clustern<\/strong><\/p>\n\n\n\n<p>Nanjing liegt im Delta des Jangtse-Flusses und verf\u00fcgt \u00fcber ein gut ausgebautes Verkehrsnetz, einen starken Strahlungseffekt sowie eine Konzentration von Universit\u00e4ten und Hochschulen mit reichhaltigen wissenschaftlichen, p\u00e4dagogischen und klinischen Ressourcen. Von der Forschung und Entwicklung von Gensequenzern bis hin zum Einsatz von Gentests in der medizinischen Behandlung und von innovativen Arzneimitteln, die in die Welt hinausgehen, bietet das Nanjing Biomedical Valley eine vollst\u00e4ndige vor- und nachgelagerte Industriekette f\u00fcr die biomedizinische Industrie, die es den Unternehmen erm\u00f6glicht, Ressourcen und Technologien effizient gemeinsam zu nutzen und die Forschung, Entwicklung und Produktion innovativer Arzneimittel zu f\u00f6rdern.<\/p>\n\n\n\n<p>Gleichzeitig wird der Schwerpunkt auf die Bed\u00fcrfnisse der biomedizinischen Industrie f\u00fcr \"Crowdsourcing+Inkubation+Beschleunigung+Industrialisierung\" gelegt.<strong>Das Nanjing Biomedical Valley bietet eine voll funktionsf\u00e4hige Tr\u00e4gerfl\u00e4che, umfassende Dienstleistungen f\u00fcr den gesamten Lebenszyklus und ein \u00f6kologisches Umfeld, das alle Faktoren der Innovation abdeckt, und hat inzwischen fast 1,9 Millionen Quadratmeter an Innovations- und Unternehmertr\u00e4gern errichtet.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/10.jpg\" alt=\"\" class=\"wp-image-12728\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/10.jpg 800w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/10-300x225.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/10-768x576.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/10-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Das Nanjing Biomedical Valley st\u00fctzt sich auf die reichhaltigen universit\u00e4ren Ressourcen der Stadt Nanjing und hat eine gro\u00dfe Zahl hochqualifizierter Talente angezogen.<strong>Bisher hat der Park 52 Experten im Rahmen des nationalen Talentprojektprogramms, 99 Talente im Rahmen des \"Shuangchuang-Plans\" der Provinz Jiangsu und 15 Top-Experten f\u00fcr Wissenschaft und Technologie in Nanjing eingef\u00fchrt. Dar\u00fcber hinaus verf\u00fcgt der Park \u00fcber 5 nationale Postdoc-Arbeitspl\u00e4tze und 8 Postdoc-Innovations- und Praxisst\u00fctzpunkte auf Provinzebene, die eine starke Unterst\u00fctzung f\u00fcr die Kultivierung und Bindung von Talenten bieten.<\/strong><\/p>\n\n\n\n<p>Durch politische Instrumente wie den \"Fast Track f\u00fcr dringend ben\u00f6tigte klinische Ger\u00e4te\" und den \"Biomedical Industry Fund\" hat Nanjing Innovationen dabei geholfen, einen nahtlosen \u00dcbergang von \"Labor - Operationssaal - Produktionslinie\" zum \"tropischen Regenwald-Effekt\" zu realisieren. \u25cb Durch politische Instrumente wie \"Fast Track for Clinically Needed Devices\" und \"Biomedical Industry Fund\" hat Nanjing Innovationen dabei geholfen, die nahtlose Verbindung von \"Labor - Operationssaal\" und \"Produktionslinie\" zu erreichen, wodurch der \"Regenwald-Effekt\" der industriellen Entwicklung entstanden ist.<\/p>\n\n\n\n<p>Zur Umsetzung der \"pr\u00e4zisen Tropfbew\u00e4sserung\" f\u00fcr biomedizinische Unternehmen hat Nanjing einen 2-Milliarden-Yuan-Mutterfonds f\u00fcr die biomedizinische Industrie eingerichtet, um Forschungs- und Entwicklungsprojekte mit positiven klinischen Phase-III-Daten oder solche, die kurz vor der Kommerzialisierung stehen, hochqualifizierte Talente mit technologischem Transformationswert sowie Fusionen und \u00dcbernahmen und Umstrukturierungen f\u00fchrender Unternehmen in den Bereichen innovative Arzneimittel, medizinische Ger\u00e4te und Biotechnologie zu unterst\u00fctzen. Schl\u00fcsselunterst\u00fctzung zur F\u00f6rderung des positiven Kreislaufs \"Wissenschaft und Technologie - Industrie - Finanzen\".<\/p>\n\n\n\n<p>Die Rekonstruktion des industriellen Musters mit \"globaler Vision + lokaler Weisheit\" bringt nicht nur die Beschleunigung der Technologie-Iteration, sondern f\u00f6rdert auch den Sprung Nanjings vom \"Made in China\" zum \"globalen Innovationszentrum\". Die \"zweiseitige Erm\u00e4chtigung\" f\u00fchrt nicht nur zu einer Beschleunigung der Technologie-Iteration, sondern f\u00f6rdert auch den Sprung Nanjings vom \"Made in China\" zur \"Quelle globaler Innovation\".<strong>Gegenw\u00e4rtig hat die biomedizinische Industrie in Nanjing einen Umfang von \u00fcber 200 Milliarden Yuan, und die umfassende Wettbewerbsf\u00e4higkeit des Nanjing Biomedical Valley liegt landesweit an achter Stelle.<\/strong>Es handelt sich um ein Demonstrationsgebiet f\u00fcr ein hochwertiges Entwicklungscluster in der Provinz Jiangsu, das erfolgreich das regionale Unterzentrum f\u00fcr Technologietransfer und biomedizinische Transformation der nationalen Universit\u00e4ten gewonnen hat und sich auf das Ziel eines 100-Milliarden-Clusters der Lebens- und Gesundheitsindustrie zubewegt.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die biomedizinische Industrie ist einer der wichtigsten industriellen Pioniercluster in Nanjing und eine der Hauptrichtungen f\u00fcr den Aufbau der industriellen St\u00e4rke und die Entwicklung neuer Produktivit\u00e4t in Nanjing. Vor kurzem hat das Netzwerk des st\u00e4dtischen Parteikomitees [...]...<\/p>","protected":false},"author":2,"featured_media":12727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-12718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-incubation_information"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u751f\u7269\u533b\u836f\u8d5b\u9053\uff0c\u5357\u4eac\u7834\u8327\u632f\u7fc5 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tigerandtech.com\/de\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u751f\u7269\u533b\u836f\u8d5b\u9053\uff0c\u5357\u4eac\u7834\u8327\u632f\u7fc5 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"og:description\" content=\"\u751f\u7269\u533b\u836f\u4ea7\u4e1a \u662f\u5357\u4eac\u91cd\u70b9\u6253\u9020\u7684\u5148\u5bfc\u4ea7\u4e1a\u96c6\u7fa4\u4e4b\u4e00 \u4e5f\u662f\u5357\u4eac\u5efa\u8bbe\u4ea7\u4e1a\u5f3a\u5e02\u3001 \u53d1\u5c55\u65b0\u8d28\u751f\u4ea7\u529b\u7684\u4e3b\u653b\u65b9\u5411 \u8fd1\u65e5\uff0c\u5e02\u59d4\u7f51 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tigerandtech.com\/de\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-12T02:54:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T02:54:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tiger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tiger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/\"},\"author\":{\"name\":\"Tiger\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880\"},\"headline\":\"\u751f\u7269\u533b\u836f\u8d5b\u9053\uff0c\u5357\u4eac\u7834\u8327\u632f\u7fc5\",\"datePublished\":\"2025-03-12T02:54:20+00:00\",\"dateModified\":\"2025-03-12T02:54:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/\"},\"wordCount\":55,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg\",\"articleSection\":[\"\u8d44\u8baf\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/\",\"url\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/\",\"name\":\"\u751f\u7269\u533b\u836f\u8d5b\u9053\uff0c\u5357\u4eac\u7834\u8327\u632f\u7fc5 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"isPartOf\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg\",\"datePublished\":\"2025-03-12T02:54:20+00:00\",\"dateModified\":\"2025-03-12T02:54:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#primaryimage\",\"url\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg\",\"contentUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.tigerandtech.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u751f\u7269\u533b\u836f\u8d5b\u9053\uff0c\u5357\u4eac\u7834\u8327\u632f\u7fc5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#website\",\"url\":\"https:\/\/www.tigerandtech.com\/de\/\",\"name\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tigerandtech.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\",\"name\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"url\":\"https:\/\/www.tigerandtech.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp\",\"contentUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp\",\"width\":1003,\"height\":116,\"caption\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880\",\"name\":\"Tiger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g\",\"caption\":\"Tiger\"},\"url\":\"https:\/\/www.tigerandtech.com\/de\/author\/tiger\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biomedizinische Schiene, Nanjing Breaking Wings - Jiangsu Xiaohu Science &amp; Technology Development Co.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tigerandtech.com\/de\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/","og_locale":"de_DE","og_type":"article","og_title":"\u751f\u7269\u533b\u836f\u8d5b\u9053\uff0c\u5357\u4eac\u7834\u8327\u632f\u7fc5 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8","og_description":"\u751f\u7269\u533b\u836f\u4ea7\u4e1a \u662f\u5357\u4eac\u91cd\u70b9\u6253\u9020\u7684\u5148\u5bfc\u4ea7\u4e1a\u96c6\u7fa4\u4e4b\u4e00 \u4e5f\u662f\u5357\u4eac\u5efa\u8bbe\u4ea7\u4e1a\u5f3a\u5e02\u3001 \u53d1\u5c55\u65b0\u8d28\u751f\u4ea7\u529b\u7684\u4e3b\u653b\u65b9\u5411 \u8fd1\u65e5\uff0c\u5e02\u59d4\u7f51 [&hellip;]","og_url":"https:\/\/www.tigerandtech.com\/de\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/","og_site_name":"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8","article_published_time":"2025-03-12T02:54:20+00:00","article_modified_time":"2025-03-12T02:54:23+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg","type":"image\/jpeg"}],"author":"Tiger","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tiger","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#article","isPartOf":{"@id":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/"},"author":{"name":"Tiger","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880"},"headline":"\u751f\u7269\u533b\u836f\u8d5b\u9053\uff0c\u5357\u4eac\u7834\u8327\u632f\u7fc5","datePublished":"2025-03-12T02:54:20+00:00","dateModified":"2025-03-12T02:54:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/"},"wordCount":55,"commentCount":0,"publisher":{"@id":"https:\/\/www.tigerandtech.com\/de\/#organization"},"image":{"@id":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg","articleSection":["\u8d44\u8baf"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/","url":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/","name":"Biomedizinische Schiene, Nanjing Breaking Wings - Jiangsu Xiaohu Science &amp; Technology Development Co.","isPartOf":{"@id":"https:\/\/www.tigerandtech.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#primaryimage"},"image":{"@id":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg","datePublished":"2025-03-12T02:54:20+00:00","dateModified":"2025-03-12T02:54:23+00:00","breadcrumb":{"@id":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#primaryimage","url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg","contentUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2025\/03\/9-1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.tigerandtech.com\/sheng_wu_yi_yao_sai_dao_nan_jing_po_jian_zhen_chi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.tigerandtech.com\/"},{"@type":"ListItem","position":2,"name":"\u751f\u7269\u533b\u836f\u8d5b\u9053\uff0c\u5357\u4eac\u7834\u8327\u632f\u7fc5"}]},{"@type":"WebSite","@id":"https:\/\/www.tigerandtech.com\/de\/#website","url":"https:\/\/www.tigerandtech.com\/de\/","name":"Jiangsu Xiaohu Technology Development Co.","description":"","publisher":{"@id":"https:\/\/www.tigerandtech.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tigerandtech.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.tigerandtech.com\/de\/#organization","name":"Jiangsu Xiaohu Technology Development Co.","url":"https:\/\/www.tigerandtech.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp","contentUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp","width":1003,"height":116,"caption":"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8"},"image":{"@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880","name":"Tiger","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g","caption":"Tiger"},"url":"https:\/\/www.tigerandtech.com\/de\/author\/tiger\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts\/12718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/comments?post=12718"}],"version-history":[{"count":0,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts\/12718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/media\/12727"}],"wp:attachment":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/media?parent=12718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/categories?post=12718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/tags?post=12718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}