{"id":15698,"date":"2026-01-19T10:13:24","date_gmt":"2026-01-19T02:13:24","guid":{"rendered":"https:\/\/www.tigerandtech.com\/?p=15698"},"modified":"2026-01-19T10:13:26","modified_gmt":"2026-01-19T02:13:26","slug":"xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li","status":"publish","type":"post","link":"https:\/\/www.tigerandtech.com\/de\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/","title":{"rendered":"Schulen und Unternehmen geben sich die Klinke in die Hand und enth\u00fcllen das gemeinsame Labor!"},"content":{"rendered":"<p class=\"has-text-align-center\">16. Januar<\/p>\n\n\n\n<p class=\"has-text-align-center\">Chinesische Pharmazeutische Universit\u00e4t und<\/p>\n\n\n\n<p class=\"has-text-align-center\">Nanjing Yizhou Food Technology Co.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Gemeinsames Labor f\u00fcr die kollaborative Innovation gesunder funktioneller Lebensmittel in der B\u00e4ckerei<\/p>\n\n\n\n<p class=\"has-text-align-center\">Einweihung des Campus der Chinesischen Pharmazeutischen Universit\u00e4t Jiangning<\/p>\n\n\n\n<p class=\"has-text-align-center\">Markierung des grenz\u00fcberschreitenden Modells \"medizinische Lebensmittel + Backen\".<\/p>\n\n\n\n<p class=\"has-text-align-center\">Einstieg in die praktische Phase<\/p>\n\n\n\n<p class=\"has-text-align-center\">Verspricht, die L\u00fccke auf dem Markt f\u00fcr funktionelle Backwaren zu schlie\u00dfen<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/111-8-1024x682.jpg\" alt=\"\" class=\"wp-image-15699\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/111-8-1024x682.jpg 1024w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/111-8-300x200.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/111-8-768x512.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/111-8-18x12.jpg 18w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/111-8.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u3000\u3000Als ma\u00dfgebliche Universit\u00e4t im Bereich Pharmazie und Biowissenschaften in China verf\u00fcgt die China Pharmaceutical University \u00fcber wissenschaftliche Forschungsvorteile bei der Erforschung funktioneller Inhaltsstoffe, der Bewertung der Bioverf\u00fcgbarkeit usw., was die Entwicklung gesunder Lebensmittel auf h\u00f6chstem Niveau unterst\u00fctzt. Nanjing Yizhou Food Technology Co., Ltd. ist der Vertreter der Lishui-Lebensmittelindustrie, hat die F\u00e4higkeit, die gesamte Industriekette zu backen, arbeitet mit mehr als 30 ber\u00fchmten Marken wie Box Ma und Three Squirrels zusammen und beliefert im Durchschnitt mehr als 300.000 Menschen pro Tag, mit einer soliden industriellen Grundlage und einem gro\u00dfen Einfluss auf den Markt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"443\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg\" alt=\"\" class=\"wp-image-15700\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg 800w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5-300x166.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5-768x425.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5-18x10.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>\u3000\u3000Yu Guangzhong dankte den Parteien in Lishui f\u00fcr ihr Vertrauen und ihre Unterst\u00fctzung f\u00fcr die Schule und erkl\u00e4rte, dass die Schule diese Zusammenarbeit als Gelegenheit nutzen werde, um die wissenschaftliche Forschung und die Ausbildung von Talenten zu vertiefen, die gemeinsame Innovation zwischen der Schule und den Unternehmen zu f\u00f6rdern, ein Labor auf hohem Niveau und eine Plattform f\u00fcr die Umsetzung von Errungenschaften aufzubauen und die Umsetzung wissenschaftlicher und technologischer Errungenschaften sowie die industrielle Modernisierung aktiv zu f\u00f6rdern.<\/p>\n\n\n\n<p>\u3000\u3000Xu Zhenghong sagte in seiner Rede, dass diese Zusammenarbeit eine wichtige Initiative zur Vertiefung der Integration von \"Industrie, Wissenschaft, Forschung und Anwendung\", zur Umsetzung der Strategie \"Gesundes China 2030\" und zur F\u00f6rderung der hochwertigen Entwicklung der regionalen Lebensmittelindustrie sei. Die Bezirksregierung von Lishui wird die Politik, die Ressourcen und die Szene unterst\u00fctzen und hofft, dass das Labor den Technologiewandel und die Markenbildung beschleunigen und der hochwertigen Entwicklung von Lishui neue Impulse verleihen wird.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/333-3-1024x682.jpg\" alt=\"\" class=\"wp-image-15701\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/333-3-1024x682.jpg 1024w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/333-3-300x200.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/333-3-768x512.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/333-3-18x12.jpg 18w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/333-3.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u3000\u3000Gest\u00fctzt auf die wissenschaftlichen Forschungsvorteile der China Pharmaceutical University und die industriellen Ressourcen von Yizhou Food wird das Joint Laboratory of Collaborative Innovation of Healthy Bakery Functional Foods den Integrationsmodus \"Medizin und Lebensmittel + B\u00e4ckerei\" erneuern und eine Reihe von funktionellen Backwaren wie Produkte mit niedrigem glyk\u00e4mischen Index, Glukose- und Fettsanierung, Gewichtsabnahme, Gesundheitspflegeprodukte usw. entwickeln, die durch das Screening von Bioextrakten und die Optimierung von Formeln die vielf\u00e4ltigen Gesundheitsanforderungen erf\u00fcllen k\u00f6nnen, wobei der Schwerpunkt auf der Segmentierung der Kundengruppen wie Diabetiker und Fitnessgruppen liegt. Durch das Screening und die Rezepturoptimierung von biologischen Extrakten konzentriert sich Yizhou Food auf die segmentierten Kundengruppen wie Diabetiker, Zucker-Lipid-Reparatur, Gewichtsabnahme, Fettabnahme, Gesundheitspflege und andere Serien von funktionellen Backwaren, um die \"Reduzierung des Zuckers, aber nicht die Reduzierung des Geschmacks\" zu erreichen und die diversifizierten Gesundheitsbed\u00fcrfnisse zu erf\u00fcllen. Gegenw\u00e4rtig hat Yizhou Food eine neue Produktionsst\u00e4tte in der Yongyang Street errichtet, die der Umsetzung von Laborergebnissen und der Produktion in gro\u00dfem Ma\u00dfstab dient. Nach der Fertigstellung der Produktionsst\u00e4tte wird ein j\u00e4hrlicher Produktionswert von etwa 800 Millionen Yuan erwartet, was die Umstellung auf eine gesunde Backtechnologie und den Aufbau einer industriellen \u00d6kologie stark f\u00f6rdern wird.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/444-3-1024x682.jpg\" alt=\"\" class=\"wp-image-15702\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/444-3-1024x682.jpg 1024w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/444-3-300x200.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/444-3-768x512.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/444-3-18x12.jpg 18w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/444-3.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u3000\u3000In den letzten Jahren hat der Distrikt Lishui die Strategie \"Produktion und Industrie\" verfolgt, neue Medizin und Leben und Gesundheit in das f\u00fchrende Industriesystem \"zwei neue und zwei weise\" integriert, sich auf den Aufbau einer kollaborativen Innovationsplattform f\u00fcr Industrie, Universit\u00e4t und Forschung konzentriert, die grenz\u00fcberschreitende Integration von Lebensmitteln und Medizin gef\u00f6rdert und eine Reihe von f\u00fchrenden Unternehmen der Branche wie Hang Seng Pharmaceutical, Yudai Pharmaceutical usw. eingef\u00fchrt. Das Unternehmen hat eine Reihe f\u00fchrender Unternehmen der Branche wie Hang Seng Pharmaceuticals, Pharmaceutical University Pharmaceuticals usw. eingef\u00fchrt. Gegenw\u00e4rtig wird der Bau des Biomedizinischen Wissenschafts- und Technologieparks Yongyang beschleunigt, wobei der Schwerpunkt auf der Ansiedlung von medizinischen Ger\u00e4ten, chemischen Arzneimitteln, traditioneller chinesischer Medizin und Gesundheit und anderen hochwertigen Unternehmen liegt, und es werden alle Anstrengungen unternommen, um ein industrielles Innovationshochland und ein Ballungsgebiet zu schaffen. 2025 hat die Produktion der neuen pharmazeutischen Industrie und der Lebens- und Gesundheitsindustrie in der Region 10,2 Milliarden Yuan \u00fcberschritten, was eine starke Entwicklungsdynamik zeigt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"428\" src=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/555-1024x428.jpg\" alt=\"\" class=\"wp-image-15703\" srcset=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/555-1024x428.jpg 1024w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/555-300x125.jpg 300w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/555-768x321.jpg 768w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/555-18x8.jpg 18w, https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/555.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Am 16. Januar wurde das Joint Laboratory for Collaborative Innovation of Healthy Bakery Functional Foods, das gemeinsam von der China Pharmaceutical University und der Nanjing Yizhou Food Science and Technology Co.<\/p>","protected":false},"author":2,"featured_media":15700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[84],"tags":[],"class_list":["post-15698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chan_ye_lian_xun_xi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u6821\u4f01\u643a\u624b\uff0c\u8054\u5408\u5b9e\u9a8c\u5ba4\u63ed\u724c\u6210\u7acb\uff01 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tigerandtech.com\/de\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u6821\u4f01\u643a\u624b\uff0c\u8054\u5408\u5b9e\u9a8c\u5ba4\u63ed\u724c\u6210\u7acb\uff01 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"og:description\" content=\"1\u670816\u65e5 \u4e2d\u56fd\u836f\u79d1\u5927\u5b66\u4e0e \u5357\u4eac\u4e00\u6d32\u98df\u54c1\u79d1\u6280\u6709\u9650\u516c\u53f8\u5171\u5efa\u7684 \u5065\u5eb7\u70d8\u7119\u529f\u80fd\u98df\u54c1\u534f\u540c\u521b\u65b0\u8054\u5408\u5b9e\u9a8c\u5ba4 \u5728\u4e2d\u56fd\u836f\u79d1\u5927\u5b66 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tigerandtech.com\/de\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-19T02:13:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T02:13:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"443\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tiger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tiger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/\"},\"author\":{\"name\":\"Tiger\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880\"},\"headline\":\"\u6821\u4f01\u643a\u624b\uff0c\u8054\u5408\u5b9e\u9a8c\u5ba4\u63ed\u724c\u6210\u7acb\uff01\",\"datePublished\":\"2026-01-19T02:13:24+00:00\",\"dateModified\":\"2026-01-19T02:13:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/\"},\"wordCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg\",\"articleSection\":[\"\u4ea7\u4e1a\u94fe\u8baf\u606f\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/\",\"url\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/\",\"name\":\"\u6821\u4f01\u643a\u624b\uff0c\u8054\u5408\u5b9e\u9a8c\u5ba4\u63ed\u724c\u6210\u7acb\uff01 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"isPartOf\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg\",\"datePublished\":\"2026-01-19T02:13:24+00:00\",\"dateModified\":\"2026-01-19T02:13:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#primaryimage\",\"url\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg\",\"contentUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg\",\"width\":800,\"height\":443},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.tigerandtech.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u6821\u4f01\u643a\u624b\uff0c\u8054\u5408\u5b9e\u9a8c\u5ba4\u63ed\u724c\u6210\u7acb\uff01\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#website\",\"url\":\"https:\/\/www.tigerandtech.com\/de\/\",\"name\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tigerandtech.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#organization\",\"name\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\",\"url\":\"https:\/\/www.tigerandtech.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp\",\"contentUrl\":\"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp\",\"width\":1003,\"height\":116,\"caption\":\"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8\"},\"image\":{\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880\",\"name\":\"Tiger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g\",\"caption\":\"Tiger\"},\"url\":\"https:\/\/www.tigerandtech.com\/de\/author\/tiger\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schulen und Unternehmen reichen sich die Hand, gemeinsames Labor eingeweiht! - Jiangsu Xiaohu Technology Development Co.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tigerandtech.com\/de\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/","og_locale":"de_DE","og_type":"article","og_title":"\u6821\u4f01\u643a\u624b\uff0c\u8054\u5408\u5b9e\u9a8c\u5ba4\u63ed\u724c\u6210\u7acb\uff01 - \u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8","og_description":"1\u670816\u65e5 \u4e2d\u56fd\u836f\u79d1\u5927\u5b66\u4e0e \u5357\u4eac\u4e00\u6d32\u98df\u54c1\u79d1\u6280\u6709\u9650\u516c\u53f8\u5171\u5efa\u7684 \u5065\u5eb7\u70d8\u7119\u529f\u80fd\u98df\u54c1\u534f\u540c\u521b\u65b0\u8054\u5408\u5b9e\u9a8c\u5ba4 \u5728\u4e2d\u56fd\u836f\u79d1\u5927\u5b66 [&hellip;]","og_url":"https:\/\/www.tigerandtech.com\/de\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/","og_site_name":"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8","article_published_time":"2026-01-19T02:13:24+00:00","article_modified_time":"2026-01-19T02:13:26+00:00","og_image":[{"width":800,"height":443,"url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg","type":"image\/jpeg"}],"author":"Tiger","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tiger","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#article","isPartOf":{"@id":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/"},"author":{"name":"Tiger","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880"},"headline":"\u6821\u4f01\u643a\u624b\uff0c\u8054\u5408\u5b9e\u9a8c\u5ba4\u63ed\u724c\u6210\u7acb\uff01","datePublished":"2026-01-19T02:13:24+00:00","dateModified":"2026-01-19T02:13:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/"},"wordCount":1,"publisher":{"@id":"https:\/\/www.tigerandtech.com\/de\/#organization"},"image":{"@id":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg","articleSection":["\u4ea7\u4e1a\u94fe\u8baf\u606f"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/","url":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/","name":"Schulen und Unternehmen reichen sich die Hand, gemeinsames Labor eingeweiht! - Jiangsu Xiaohu Technology Development Co.","isPartOf":{"@id":"https:\/\/www.tigerandtech.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#primaryimage"},"image":{"@id":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg","datePublished":"2026-01-19T02:13:24+00:00","dateModified":"2026-01-19T02:13:26+00:00","breadcrumb":{"@id":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#primaryimage","url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg","contentUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2026\/01\/222-5.jpg","width":800,"height":443},{"@type":"BreadcrumbList","@id":"https:\/\/www.tigerandtech.com\/xiao_qi_xie_shou_lian_he_shi_yan_shi_jie_pai_cheng_li\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.tigerandtech.com\/"},{"@type":"ListItem","position":2,"name":"\u6821\u4f01\u643a\u624b\uff0c\u8054\u5408\u5b9e\u9a8c\u5ba4\u63ed\u724c\u6210\u7acb\uff01"}]},{"@type":"WebSite","@id":"https:\/\/www.tigerandtech.com\/de\/#website","url":"https:\/\/www.tigerandtech.com\/de\/","name":"Jiangsu Xiaohu Technology Development Co.","description":"","publisher":{"@id":"https:\/\/www.tigerandtech.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tigerandtech.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.tigerandtech.com\/de\/#organization","name":"Jiangsu Xiaohu Technology Development Co.","url":"https:\/\/www.tigerandtech.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp","contentUrl":"https:\/\/www.tigerandtech.com\/wp-content\/uploads\/2024\/04\/LOGO.webp","width":1003,"height":116,"caption":"\u6c5f\u82cf\u5c0f\u864e\u79d1\u6280\u53d1\u5c55\u6709\u9650\u516c\u53f8"},"image":{"@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/51ec609ae6cc9628108b1c3c12edd880","name":"Tiger","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.tigerandtech.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1268fadb8bcdc9715735dec85d39bd3ab930575d669e52df7d55917ff603a684?s=96&d=mm&r=g","caption":"Tiger"},"url":"https:\/\/www.tigerandtech.com\/de\/author\/tiger\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts\/15698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/comments?post=15698"}],"version-history":[{"count":0,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/posts\/15698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/media\/15700"}],"wp:attachment":[{"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/media?parent=15698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/categories?post=15698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tigerandtech.com\/de\/wp-json\/wp\/v2\/tags?post=15698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}